{"id":55535,"date":"2026-03-20T10:00:02","date_gmt":"2026-03-20T14:00:02","guid":{"rendered":"https:\/\/ehrc.ca\/?p=55535"},"modified":"2026-07-27T14:10:52","modified_gmt":"2026-07-27T18:10:52","slug":"la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne","status":"publish","type":"post","link":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/","title":{"rendered":"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne"},"content":{"rendered":"<p><span data-contrast=\"auto\">Il y a quelques ann\u00e9es, j\u2019ai \u00e9t\u00e9 t\u00e9moin d\u2019une situation qui m\u2019a profond\u00e9ment marqu\u00e9. Alex (nom fictif),\u00a0un\u00b7e\u00a0ancien\u00b7ne\u00a0coll\u00e8gue, a re\u00e7u un diagnostic de TDAH. Au lieu de se voir accorder les mesures d\u2019adaptation et le soutien n\u00e9cessaires pour continuer \u00e0 contribuer efficacement au travail, Alex a \u00e9t\u00e9\u00a0mis\u00b7e\u00a0en cong\u00e9 d\u2019invalidit\u00e9 de courte dur\u00e9e. La d\u00e9cision n\u2019\u00e9tait pas mal intentionn\u00e9e; elle reposait plut\u00f4t sur un manque de compr\u00e9hension et sur la croyance erron\u00e9e selon laquelle les\u00a0employ\u00e9\u00b7e\u00b7s\u00a0neurodivers\u00b7es\u00a0sont \u00ab\u202ftrop difficiles\u202f\u00bb \u00e0 g\u00e9rer.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Si les bonnes informations, les outils n\u00e9cessaires et une formation appropri\u00e9e avaient \u00e9t\u00e9 en place, la situation aurait pu \u00e9voluer tout autrement. Ce qu\u2019a v\u00e9cu Alex n\u2019est pas un cas isol\u00e9. Son exp\u00e9rience met en lumi\u00e8re les enjeux syst\u00e9matiques r\u00e9pandus au sein de la main-d\u2019\u0153uvre canadienne.\u00a0<\/span><\/p>\n<h3><b><span data-contrast=\"auto\"><span class=\"TextRun SCXW245782070 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW245782070 BCX8\">Le potentiel inexploit\u00e9 de la neurodiversit\u00e9<\/span><\/span><span class=\"EOP Selected SCXW245782070 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/span><\/b><\/h3>\n<p><span data-contrast=\"auto\">La neurodiversit\u00e9 renvoie aux diff\u00e9rences naturelles rencontr\u00e9es dans les modes de pens\u00e9e, dans les traitements de l\u2019information et dans les interactions avec l\u2019environnement. Elle englobe les personnes autistes, avec un TDAH, atteintes de dyslexie ou pr\u00e9sentant d\u2019autres variations neurologiques. Ces troubles ne sont pas des d\u00e9ficits. Les personnes neurodivergentes mettent souvent \u00e0 contribution des comp\u00e9tences exceptionnelles, telles que la cr\u00e9ativit\u00e9, la capacit\u00e9 \u00e0 r\u00e9soudre des probl\u00e8mes de fa\u00e7on innovante, la reconnaissance des formes et le sens du d\u00e9tail, qui sont toutes des comp\u00e9tences de plus en plus pris\u00e9es dans une \u00e9conomie caract\u00e9ris\u00e9e par la complexit\u00e9, l\u2019adaptabilit\u00e9 et l\u2019innovation.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Malgr\u00e9 ces atouts, les personnes\u00a0neurodiverses\u00a0sont consid\u00e9rablement sous-repr\u00e9sent\u00e9es dans la main-d\u2019\u0153uvre. Selon l\u2019<\/span><a href=\"https:\/\/www150.statcan.gc.ca\/n1\/daily-quotidien\/231201\/dq231201b-fra.htm\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Enqu\u00eate canadienne sur l\u2019incapacit\u00e9 de 2022<\/span><\/a><span data-contrast=\"auto\">, 62\u202f% des adultes en \u00e2ge de travailler et en situation de handicap occupaient un emploi, comparativement \u00e0 78\u202f% des personnes sans incapacit\u00e9. L\u2019\u00e9cart est encore plus frappant chez les adultes autistes\u202f: seules 33\u202f% des personnes autistes \u00e2g\u00e9es de 20 \u00e0 64\u202fans \u00e9taient employ\u00e9es. Les donn\u00e9es r\u00e9centes sur le march\u00e9 du travail confirment que ce probl\u00e8me n\u2019est pas r\u00e9solu.\u00a0En 2024,\u00a0<\/span><a href=\"https:\/\/www150.statcan.gc.ca\/n1\/pub\/71-222-x\/71-222-x2025001-fra.htm\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Statistique Canada<\/span><\/a><span data-contrast=\"auto\">\u00a0a fait \u00e9tat d\u2019un taux d\u2019emploi de 46,4\u202f% pour les personnes en situation de handicap, par rapport \u00e0 66,2\u202f% pour les personnes sans incapacit\u00e9, avec des \u00e9carts de participation toujours importants dans toutes les provinces et tous les groupes d\u2019\u00e2ge.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ces \u00e9carts n\u2019ont rien \u00e0 voir avec les capacit\u00e9s. Ils t\u00e9moignent des syst\u00e8mes qui continuent de privil\u00e9gier des visions \u00e9troites de la communication, de la productivit\u00e9 et du professionnalisme. Une \u00e9tude men\u00e9e par\u00a0<\/span><a href=\"https:\/\/www.deloitte.com\/ca\/en\/who-we-are\/press-room\/new-report-by-deloitte-canada-and-auticon-canada-finds-employment-barriers-lack-of-workplace-support-for-autistic-community.html\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Deloitte Canada et auticon Canada<\/span><\/a><span data-contrast=\"auto\">\u00a0a r\u00e9v\u00e9l\u00e9 que beaucoup de\u00a0travailleur\u00b7euse\u00b7s\u00a0autistes sont encore\u00a0sous-repr\u00e9sent\u00e9\u00b7e\u00b7s\u00a0et\u00a0sous-employ\u00e9\u00b7e\u00b7s\u00a0malgr\u00e9 leur potentiel, et que pr\u00e8s de la moiti\u00e9 d\u2019entre\u00a0eux\u00b7elles\u00a0ne se sentent pas \u00e0 l\u2019aise de d\u00e9voiler leur\u00a0neurodivergence\u00a0au travail. Cela souligne que le probl\u00e8me r\u00e9side dans la culture du lieu de travail, et non dans le talent des\u00a0employ\u00e9\u00b7e\u00b7s. La conception des t\u00e2ches, les pratiques de recrutement, les environnements sensoriels, les attentes s\u00e9v\u00e8res en mati\u00e8re de rendement et les proc\u00e9dures d\u2019adaptation insuffisantes continuent d\u2019exclure les personnes dont les modes de pens\u00e9e ne correspondent pas aux normes conventionnelles.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Le r\u00e9sultat\u202f: une perte importante pour le Canada, tant sur le plan de la productivit\u00e9 que par l\u2019exclusion des personnes talentueuses qui peuvent et veulent contribuer de mani\u00e8re importante \u00e0 l\u2019\u00e9conomie. Les milieux de travail qui ne s\u2019adaptent pas passent \u00e0 c\u00f4t\u00e9 de bien plus que des comp\u00e9tences. Ils maintiennent des barri\u00e8res qui pourraient \u00eatre \u00e9vit\u00e9es et qui limitent la pleine participation des personnes comp\u00e9tentes.<\/span><\/p>\n<h3><span data-ccp-props=\"{}\"><span class=\"TextRun SCXW153809458 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW153809458 BCX8\">Les co\u00fbts cach\u00e9s du masquage<\/span><\/span><span class=\"EOP Selected SCXW153809458 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/span><\/h3>\n<p><span data-contrast=\"auto\">Beaucoup de personnes\u00a0neurodiverses\u00a0deviennent expertes en \u00ab\u202fmasquage\u202f\u00bb\u202f: elles r\u00e9priment ou dissimulent consciemment des aspects de leur\u00a0neurodivergence\u00a0pour se conformer aux normes du lieu de travail. Le masquage peut consister \u00e0 r\u00e9duire les comportements d\u2019autostimulation, \u00e0 reproduire les signaux sociaux ou \u00e0 g\u00e9rer l\u2019impulsivit\u00e9 sans que personne ne le remarque.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Si le masquage permet aux personnes de se fondre dans l\u2019environnement professionnel, il a n\u00e9anmoins un co\u00fbt consid\u00e9rable. L\u2019effort continu devant \u00eatre d\u00e9ploy\u00e9 pour para\u00eetre \u00ab\u202fnormal\u202f\u00bb peut provoquer de l\u2019anxi\u00e9t\u00e9, une d\u00e9pression, de l\u2019\u00e9puisement et un surmenage. Il dissimule aussi les comp\u00e9tences r\u00e9elles de ces\u00a0employ\u00e9\u00b7e\u00b7s, tout en renfor\u00e7ant les st\u00e9r\u00e9otypes et en alimentant un cycle de sous-utilisation et de m\u00e9compr\u00e9hension.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h3><span data-ccp-props=\"{}\"><span class=\"TextRun SCXW97224557 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW97224557 BCX8\">La r\u00e9volution de la main-d\u2019\u0153uvre<\/span><\/span><span class=\"EOP Selected SCXW97224557 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/span><\/h3>\n<p><span class=\"TextRun SCXW14032472 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW14032472 BCX8\">La cr\u00e9ation de milieux de travail v\u00e9ritablement inclusifs n\u00e9cessite des gestes intentionnels. Voici quelques pistes pour les organisations\u202f:<\/span><\/span><span class=\"EOP Selected SCXW14032472 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h4><b><\/b>1. <span class=\"NormalTextRun SCXW87357921 BCX8\">Normaliser les politiques et les pratiques<\/span><\/h4>\n<p><span class=\"TextRun SCXW201541159 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201541159 BCX8\">Des lignes directrices claires et uniformes assurent un soutien \u00e9quitable aux\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201541159 BCX8\">employ\u00e9\u00b7e\u00b7s<\/span><span class=\"NormalTextRun SCXW201541159 BCX8\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201541159 BCX8\">neurodivers\u00b7es<\/span><span class=\"NormalTextRun SCXW201541159 BCX8\">. Cela comprend\u202f:\u00a0<\/span><\/span><\/p>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span class=\"TextRun SCXW169722005 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW169722005 BCX8\">Des modalit\u00e9s de travail flexibles<\/span><\/span><span class=\"EOP Selected SCXW169722005 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span class=\"TextRun SCXW93974277 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW93974277 BCX8\">Des modifications de t\u00e2ches<\/span><\/span><\/li>\n<\/ul>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span class=\"TextRun SCXW37676290 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW37676290 BCX8\">Des espaces de travail adapt\u00e9s aux sensibilit\u00e9s sensorielles<\/span><\/span><span class=\"EOP Selected SCXW37676290 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span class=\"TextRun SCXW81099367 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW81099367 BCX8\">Des normes de communication claires<\/span><\/span><\/li>\n<\/ul>\n<p><span class=\"TextRun SCXW84246947 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84246947 BCX8\">La normalisation fait de l\u2019inclusion une norme, et non un choix.<\/span><\/span><\/p>\n<h4><b><\/b>2. <span class=\"NormalTextRun SCXW190884673 BCX8\">\u00a0<\/span><span class=\"NormalTextRun SCXW190884673 BCX8\">Investir dans la formation et les outils<\/span><\/h4>\n<p><span class=\"TextRun SCXW194861645 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW194861645 BCX8\">Les\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW194861645 BCX8\">professionnel\u00b7le\u00b7s<\/span><span class=\"NormalTextRun SCXW194861645 BCX8\">\u00a0des RH, les gestionnaires et les\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW194861645 BCX8\">dirigeant\u00b7e\u00b7s<\/span><span class=\"NormalTextRun SCXW194861645 BCX8\"> gagnent \u00e0 suivre sur une formation sur la neurodiversit\u00e9. La formation leur permet de\u202f:<\/span><\/span><\/p>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span class=\"TextRun SCXW50503737 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW50503737 BCX8\">Reconna\u00eetre<\/span><span class=\"NormalTextRun SCXW50503737 BCX8\">\u00a0les forces des personnes\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW50503737 BCX8\">neurodiverses<\/span><span class=\"NormalTextRun SCXW50503737 BCX8\">;<\/span><\/span><span class=\"EOP Selected SCXW50503737 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span class=\"TextRun SCXW92387308 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW92387308 BCX8\">Mettre<\/span><span class=\"NormalTextRun SCXW92387308 BCX8\">\u00a0en \u0153uvre des mesures d\u2019adaptation efficaces;<\/span><\/span><span class=\"EOP Selected SCXW92387308 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"7\" data-aria-level=\"1\"><span class=\"TextRun SCXW192964587 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW192964587 BCX8\">Mettre<\/span><span class=\"NormalTextRun SCXW192964587 BCX8\">\u00a0en place des outils de recrutement et d\u2019\u00e9valuation inclusifs et adapt\u00e9s \u00e0 la neurodiversit\u00e9;<\/span><\/span><span class=\"EOP Selected SCXW192964587 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"8\" data-aria-level=\"1\"><span class=\"TextRun SCXW172473425 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW172473425 BCX8\">All\u00e9ger<\/span><span class=\"NormalTextRun SCXW172473425 BCX8\">\u00a0la pression incitant les\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW172473425 BCX8\">employ\u00e9\u00b7e\u00b7s<\/span><span class=\"NormalTextRun SCXW172473425 BCX8\">\u00a0\u00e0 dissimuler leur\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW172473425 BCX8\">neurodivergence<\/span><span class=\"NormalTextRun SCXW172473425 BCX8\">.<\/span><\/span><span class=\"EOP Selected SCXW172473425 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><span class=\"TextRun SCXW99195353 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW99195353 BCX8\">Les bons outils et les connaissances appropri\u00e9es permettent aux \u00e9quipes de mieux soutenir les talents.<\/span><\/span><\/p>\n<h4><b><\/b>3. <span class=\"TextRun SCXW133172916 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW133172916 BCX8\">Collaborer avec des\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW133172916 BCX8\">professionnel\u00b7le\u00b7s<\/span><\/span><span class=\"EOP SCXW133172916 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/h4>\n<p><span class=\"NormalTextRun SCXW26180941 BCX8\">Collaborer avec des organisations sp\u00e9cialis\u00e9es en neurodiversit\u00e9 et en inclusion au travail permet d\u2019acc\u00e9der\u00a0<\/span><span class=\"NormalTextRun SCXW26180941 BCX8\">\u00e0 une expertise, \u00e0 des m\u00e9canismes de responsabilisation et \u00e0 des strat\u00e9gies \u00e9prouv\u00e9es. Ces partenariats contribuent \u00e0 mettre en place des pratiques d\u2019inclusion durables et fond\u00e9es sur des donn\u00e9es probantes.<\/span><\/p>\n<h3><span data-ccp-props=\"{}\"><span class=\"TextRun SCXW246343559 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW246343559 BCX8\">Le co\u00fbt de l\u2019inaction<\/span><\/span><span class=\"EOP Selected SCXW246343559 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/span><\/h3>\n<p><span data-contrast=\"auto\">Le Canada conna\u00eet une p\u00e9nurie de main-d\u2019\u0153uvre de plus en plus importante. Parall\u00e8lement, les talents neurodivergents demeurent sous-exploit\u00e9s, non pas par manque de comp\u00e9tences, mais en raison d\u2019un manque de pr\u00e9paration organisationnelle. Rem\u00e9dier \u00e0 cette situation est \u00e0 la fois n\u00e9cessaire\u00a0et\u00a0constitue une occasion strat\u00e9gique.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Les organisations qui valorisent la neurodiversit\u00e9 ont acc\u00e8s \u00e0 un plus grand bassin de talents, \u00e0 une capacit\u00e9 d\u2019innovation accrue et \u00e0 des cultures de travail plus inclusives et solides.\u00a0Toutefois, pour parvenir \u00e0 ces r\u00e9sultats, il faut un investissement r\u00e9fl\u00e9chi, un changement de perspective et un effort pour \u00e9liminer les id\u00e9es pr\u00e9con\u00e7ues d\u00e9pass\u00e9es.\u00a0<\/span><span data-ccp-props=\"{&quot;335559739&quot;:0}\">\u00a0<\/span><\/p>\n<h3><span data-ccp-props=\"{}\"><span class=\"TextRun SCXW86700553 BCX8\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun CommentStart SCXW86700553 BCX8\">Un appel \u00e0 l\u2019action<\/span><\/span><span class=\"EOP Selected SCXW86700553 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/span><\/h3>\n<p><span data-contrast=\"auto\">Exploiter les forces des\u00a0Canadien\u00b7ne\u00b7s\u00a0neurodivers\u00b7es\u00a0nous permet de rem\u00e9dier aux p\u00e9nuries de main-d\u2019\u0153uvre et de b\u00e2tir un effectif plus inclusif et innovant.\u00a0L\u2019histoire d\u2019Alex n\u2019aurait pas d\u00fb se d\u00e9rouler ainsi\u202f\u2013 et avec les bons soutiens en place, cela ne devrait pratiquement jamais se produire.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Il reste \u00e0 voir si les organisations sont pr\u00eates \u00e0 aller au-del\u00e0 de la simple sensibilisation et \u00e0 passer aux actions concr\u00e8tes.<\/span><span data-ccp-props=\"{&quot;335559739&quot;:0}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a quelques ann\u00e9es, j\u2019ai \u00e9t\u00e9 t\u00e9moin d\u2019une situation qui m\u2019a profond\u00e9ment marqu\u00e9. Alex (nom fictif),\u00a0un\u00b7e\u00a0ancien\u00b7ne\u00a0coll\u00e8gue, a re\u00e7u un diagnostic de TDAH. Au lieu de se voir accorder les [&hellip;]<\/p>\n","protected":false},"author":968,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[269],"tags":[],"audience":[181,221,172],"topic":[250],"news_year_published":[323],"news_type":[255],"class_list":["post-55535","post","type-post","status-publish","format-standard","hentry","category-blog-fr","audience-job-seekers-fr","audience-employers-fr","audience-hr-managers-fr","topic-diversity-equity-inclusion-dei-fr","news_year_published-323","news_type-blog-post-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne - EHRC<\/title>\n<meta name=\"description\" content=\"Il y a quelques ann\u00e9es, j\u2019ai \u00e9t\u00e9 t\u00e9moin d\u2019une situation qui m\u2019a profond\u00e9ment marqu\u00e9. Alex (nom fictif),\u00a0un\u00b7e\u00a0ancien\u00b7ne\u00a0coll\u00e8gue, a re\u00e7u un diagnostic de TDAH. Au lieu de se voir accorder les [&hellip;]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne - EHRC\" \/>\n<meta property=\"og:description\" content=\"Il y a quelques ann\u00e9es, j\u2019ai \u00e9t\u00e9 t\u00e9moin d\u2019une situation qui m\u2019a profond\u00e9ment marqu\u00e9. Alex (nom fictif),\u00a0un\u00b7e\u00a0ancien\u00b7ne\u00a0coll\u00e8gue, a re\u00e7u un diagnostic de TDAH. Au lieu de se voir accorder les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/\" \/>\n<meta property=\"og:site_name\" content=\"EHRC\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T14:00:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-27T18:10:52+00:00\" \/>\n<meta name=\"author\" content=\"Muhammad Ahsan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Muhammad Ahsan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/\"},\"author\":{\"name\":\"Muhammad Ahsan\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/#\\\/schema\\\/person\\\/efee749e6a581aee86508278ace4f377\"},\"headline\":\"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne\",\"datePublished\":\"2026-03-20T14:00:02+00:00\",\"dateModified\":\"2026-07-27T18:10:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/\"},\"wordCount\":1242,\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/\",\"url\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/\",\"name\":\"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne - EHRC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ehrc.ca\\\/#website\"},\"datePublished\":\"2026-03-20T14:00:02+00:00\",\"dateModified\":\"2026-07-27T18:10:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ehrc.ca\\\/#\\\/schema\\\/person\\\/efee749e6a581aee86508278ace4f377\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/#website\",\"url\":\"https:\\\/\\\/ehrc.ca\\\/\",\"name\":\"EHRC\",\"description\":\"Improving our industry, together.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ehrc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/#\\\/schema\\\/person\\\/efee749e6a581aee86508278ace4f377\",\"name\":\"Muhammad Ahsan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d8d0dca61eace328e3c00eaa58348adf7658c5ec91bd3084f8ea6b9394a92ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d8d0dca61eace328e3c00eaa58348adf7658c5ec91bd3084f8ea6b9394a92ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d8d0dca61eace328e3c00eaa58348adf7658c5ec91bd3084f8ea6b9394a92ab?s=96&d=mm&r=g\",\"caption\":\"Muhammad Ahsan\"},\"url\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/author\\\/ahsan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne - EHRC","description":"Il y a quelques ann\u00e9es, j\u2019ai \u00e9t\u00e9 t\u00e9moin d\u2019une situation qui m\u2019a profond\u00e9ment marqu\u00e9. Alex (nom fictif),\u00a0un\u00b7e\u00a0ancien\u00b7ne\u00a0coll\u00e8gue, a re\u00e7u un diagnostic de TDAH. Au lieu de se voir accorder les [&hellip;]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/","og_locale":"fr_FR","og_type":"article","og_title":"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne - EHRC","og_description":"Il y a quelques ann\u00e9es, j\u2019ai \u00e9t\u00e9 t\u00e9moin d\u2019une situation qui m\u2019a profond\u00e9ment marqu\u00e9. Alex (nom fictif),\u00a0un\u00b7e\u00a0ancien\u00b7ne\u00a0coll\u00e8gue, a re\u00e7u un diagnostic de TDAH. Au lieu de se voir accorder les [&hellip;]","og_url":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/","og_site_name":"EHRC","article_published_time":"2026-03-20T14:00:02+00:00","article_modified_time":"2026-07-27T18:10:52+00:00","author":"Muhammad Ahsan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Muhammad Ahsan","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/#article","isPartOf":{"@id":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/"},"author":{"name":"Muhammad Ahsan","@id":"https:\/\/ehrc.ca\/#\/schema\/person\/efee749e6a581aee86508278ace4f377"},"headline":"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne","datePublished":"2026-03-20T14:00:02+00:00","dateModified":"2026-07-27T18:10:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/"},"wordCount":1242,"articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/","url":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/","name":"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne - EHRC","isPartOf":{"@id":"https:\/\/ehrc.ca\/#website"},"datePublished":"2026-03-20T14:00:02+00:00","dateModified":"2026-07-27T18:10:52+00:00","author":{"@id":"https:\/\/ehrc.ca\/#\/schema\/person\/efee749e6a581aee86508278ace4f377"},"breadcrumb":{"@id":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ehrc.ca\/fr\/la-neurodiversite-au-travail-une-occasion-ratee-pour-la-main-doeuvre-canadienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ehrc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"La neurodiversit\u00e9 au travail\u202f: une occasion rat\u00e9e pour la main-d\u2019\u0153uvre canadienne"}]},{"@type":"WebSite","@id":"https:\/\/ehrc.ca\/#website","url":"https:\/\/ehrc.ca\/","name":"EHRC","description":"Improving our industry, together.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ehrc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ehrc.ca\/#\/schema\/person\/efee749e6a581aee86508278ace4f377","name":"Muhammad Ahsan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5d8d0dca61eace328e3c00eaa58348adf7658c5ec91bd3084f8ea6b9394a92ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d8d0dca61eace328e3c00eaa58348adf7658c5ec91bd3084f8ea6b9394a92ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d8d0dca61eace328e3c00eaa58348adf7658c5ec91bd3084f8ea6b9394a92ab?s=96&d=mm&r=g","caption":"Muhammad Ahsan"},"url":"https:\/\/ehrc.ca\/fr\/author\/ahsan\/"}]}},"_links":{"self":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/posts\/55535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/users\/968"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=55535"}],"version-history":[{"count":1,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/posts\/55535\/revisions"}],"predecessor-version":[{"id":55536,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/posts\/55535\/revisions\/55536"}],"wp:attachment":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=55535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=55535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=55535"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/audience?post=55535"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/topic?post=55535"},{"taxonomy":"news_year_published","embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/news_year_published?post=55535"},{"taxonomy":"news_type","embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/news_type?post=55535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}