{"id":48057,"date":"2022-11-30T05:47:41","date_gmt":"2022-11-30T10:47:41","guid":{"rendered":"https:\/\/ehrc-rebuild.paperleaftest.com\/funding\/"},"modified":"2026-07-23T18:53:34","modified_gmt":"2026-07-23T22:53:34","slug":"financement","status":"publish","type":"page","link":"https:\/\/ehrc.ca\/fr\/financement\/","title":{"rendered":"Financement et incitatifs \u00e0 l\u2019embauche"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"template-landing-page.php","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[182,168],"class_list":["post-48057","page","type-page","status-publish","hentry","category-funding-fr","category-priority-areas-fr"],"acf":{"page_header":{"":null,"description":"C\u2019est simple\u00a0: la plateforme Financer l\u2019avenir facilite le processus de demande et de gestion des subventions salariales et des incitatifs \u00e0 l\u2019embauche.","link":{"title":"Demande de financement","url":"https:\/\/ehrc.fundingforfutures.ca\/fr\/","target":"_blank"},"image_id":44437,"image_alt_text":"Lignes \u00e9lectriques la nuit"},"pagebuilder":[{"acf_fc_layout":"columned_icon_cards","heading":"Nos programmes","description":"Le secteur canadien de l\u2019\u00e9lectricit\u00e9 est en pleine croissance. Les pr\u00e9visions actuelles indiquent que la capacit\u00e9 de production, de transport et de distribution sera deux \u00e0 trois fois plus importante d\u2019ici 2050. Cela signifie qu\u2019une main-d\u2019\u0153uvre grandissante sera requise pour construire, exploiter et entretenir cette nouvelle infrastructure carboneutre. RHIEC propose des subventions salariales et des incitatifs \u00e0 l\u2019embauche pour aider les employeur\u00b7euse\u00b7s \u00e0 recruter leurs futur\u00b7e\u00b7s employ\u00e9\u00b7e\u00b7s, offrant ainsi \u00e0 une nouvelle g\u00e9n\u00e9ration de talents la possibilit\u00e9 de travailler dans ce secteur en pleine croissance.","link":"","icon_rows":[{"icon_cards":[{"image_id":46988,"image_alt_text":"Discovering Potential icon","image_size":"small","heading":"D\u00e9couverte de potentiels","content":"Le programme D\u00e9couverte de potentiels est une initiative canadienne de placement des jeunes dans l\u2019industrie de l\u2019\u00e9lectricit\u00e9. Il offre des subventions pouvant aller jusqu\u2019\u00e0 $22,000 aux employeurs qui cr\u00e9ent des stages ou des possibilit\u00e9s de formation en cours d\u2019emploi pertinents et significatifs.\r\n\r\n<em>RHIEC priorise actuellement les demandes pour des postes en STIM destin\u00e9s aux femmes.<\/em>","link":{"title":"Pour en savoir plus","url":"https:\/\/ehrc.ca\/fr\/programs\/decouverte-de-potentiels\/","target":""},"custom_navigation_label":""},{"image_id":46990,"image_alt_text":"Empowering futures icon","image_size":"small","heading":"Impulser l\u2019avenir","content":"Octroi d'une aide financi\u00e8re pouvant aller jusqu'\u00e0 5 000 dollars aux employeurs qui cr\u00e9ent de nouvelles opportunit\u00e9s d'apprentissage en milieu professionnel (AMP) pour les \u00e9tudiants.","link":{"title":"Pour en savoir plus","url":"https:\/\/ehrc.ca\/fr\/programs\/impulser-l-avenir\/","target":""},"custom_navigation_label":""},{"image_id":46994,"image_alt_text":"Destination M\u00e9tiers","image_size":"small","heading":"Destination M\u00e9tiers","content":"Le programme soutient les employeurs qui cr\u00e9ent de nouvelles possibilit\u00e9s d\u2019apprentissage int\u00e9gr\u00e9 au travail (AIT) dans le secteur de l\u2019\u00e9lectricit\u00e9, en offrant des subventions de 5\u2009000 $ par poste.\u200b","link":{"title":"Pour en savoir plus","url":"https:\/\/ehrc.ca\/fr\/programs\/destination-metiers\/","target":""},"custom_navigation_label":""}]}],"custom_navigation_label":""},{"acf_fc_layout":"content_block","background_colour":"--ehrc-light-grey","heading":"\u00c0 propos de Financer l\u2019avenir","description":"Un soutien pour les nouveaux\u00b7elles arrivant\u00b7e\u00b7s au Canada, les jeunes, les \u00e9l\u00e8ves et les apprenti\u00b7e\u00b7s de de troisi\u00e8me et quatri\u00e8me ann\u00e9e. ","rows":[{"acf_fc_layout":"two_columns","column_1":{"type":"text","content":"<div class=\"container\">\r\n<div class=\"row\">\r\n<div class=\"col-12 col-lg-7\">\r\n<div class=\"inner-banner-container\">\r\n<h3 class=\"heading\">Recevoir du financement n'a jamais \u00e9t\u00e9 aussi facile<\/h3>\r\n<p class=\"text\">La plateforme Financer l\u2019avenir simplifie votre acc\u00e8s aux programmes de financement et aux incitatifs \u00e0 l\u2019embauche, simplifiant la gestion des candidatures, le suivi du statut et les processus de r\u00e9clamation et de paiement pour votre nouvelle embauche.<\/p>\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<p class=\"button-primary\"><a class=\"link wysiwyg-button button-secondary\" href=\"http:\/\/ehrc.fundingforfutures.ca\/fr\" target=\"_blank\" rel=\"noopener\">Visiter la plateforme Financer l\u2019avenir<\/a><\/p>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""},"column_2":{"type":"image","content":"<h4><img class=\"alignnone size-medium wp-image-52303\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-2.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<h5>Participant sends eligibility form<\/h5>","aspect_ratio":"auto","visual_accent":false,"":null,"image_id":42725,"image_alt_text":"Plateforme Financer l\u2019avenir"}}],"custom_navigation_label":""},{"acf_fc_layout":"content_block","background_colour":"--ehrc-white","heading":"Financer l'avenir processus de gestion des placements","description":"<p class=\"body-large\">Learn about the funding programs available to electricity employers like you.<\/p>\r\nOur Funding Forum webinar explores which funding programs are right for you, and how they're designed to help employers recruit and retain youth, students, apprentices and new entrants to the industry.","rows":[{"acf_fc_layout":"three_columns","column_1":{"type":"text","content":"<h4><img class=\"alignnone wp-image-52301 size-full\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-1.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<div class=\"step\">\r\n<h5 class=\"step-title title-4\">Demande de financement<\/h5>\r\n<p class=\"step-content\">L'employeur remplit une demande en ligne pour les stages qu'il souhaite voir financ\u00e9s.<\/p>\r\n\r\n<\/div>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""},"column_2":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52303\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-2.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<div class=\"step\">\r\n<h5 class=\"step-title title-4\">\u00c9ligibilit\u00e9 des participants<\/h5>\r\n<p class=\"step-content\">Le participant remplit un formulaire d'\u00e9ligibilit\u00e9 en ligne envoy\u00e9 \u00e0 son courriel.<\/p>\r\n\r\n<\/div>","aspect_ratio":"auto","visual_accent":false,"":null,"image_id":42725,"image_alt_text":"Funding for Futures Platform"},"column_3":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52305\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-3.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<div class=\"step\">\r\n<h5 class=\"step-title title-4\">Examen des candidatures<\/h5>\r\n<p class=\"step-content\">La demande est examin\u00e9e. Le d\u00e9lai de traitement peut aller jusqu'\u00e0 10 jours ouvrables.<\/p>\r\n\r\n<\/div>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""}},{"acf_fc_layout":"three_columns","column_1":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52307\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-4.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<div class=\"step\">\r\n<h5 class=\"step-title title-4\">Contrat<\/h5>\r\n<p class=\"step-content\">Contrat pour les stages approuv\u00e9s est sign\u00e9 par l'employeur, le participant et Organisation de la livraison.<\/p>\r\n\r\n<\/div>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""},"column_2":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52309\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-5.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<div class=\"step\">\r\n<h5 class=\"step-title title-4\">Plan d'apprentissage<\/h5>\r\n<p class=\"step-content\">L'employeur et le participant \u00e9laborent ensemble un plan d'apprentissage.<\/p>\r\n\r\n<\/div>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""},"column_3":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52311\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-6.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<div class=\"step\">\r\n<h5 class=\"step-title title-4\">Demandes de remboursement<\/h5>\r\n<p class=\"step-content\">L'employeur soumet des demandes de remboursement mensuelles.<\/p>\r\n\r\n<\/div>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""}},{"acf_fc_layout":"three_columns","column_1":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52313\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-7.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<h5 class=\"step-title title-4\">Enqu\u00eate d'\u00e9valuation des employeurs<\/h5>\r\n<p class=\"step-content\">L'employeur re\u00e7oit un questionnaire d'\u00e9valuation en ligne sur le stage.<\/p>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""},"column_2":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52315\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-8.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<h5 class=\"step-title title-4\">Enqu\u00eate d'\u00e9valuation des participants<\/h5>\r\n<p class=\"step-content\">Le participant re\u00e7oit un questionnaire d'\u00e9valuation en ligne sur le stage.<\/p>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""},"column_3":{"type":"text","content":"<h4><img class=\"alignnone size-medium wp-image-52317\" src=\"https:\/\/ehrc.ca\/wp-content\/uploads\/2023\/06\/EHRC-FFF-Process-Step-9.jpg\" alt=\"\" width=\"300\" height=\"157\" \/><\/h4>\r\n<div class=\"about-section\">\r\n<div class=\"container\">\r\n<div class=\"row d-flex justify-content-center\">\r\n<div class=\"col-12\">\r\n<div class=\"step-wrapper\">\r\n<div class=\"step\">\r\n<h5 class=\"step-title title-4\">Terminaison<\/h5>\r\n<p class=\"step-title title-4\">Le placement financ\u00e9 prend fin.<\/p>\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""}}],"custom_navigation_label":""},{"acf_fc_layout":"content_block","background_colour":"--ehrc-light-grey","heading":"Le changement est parfois difficile","description":"RHIEC a mis en place une s\u00e9rie de programmes de financement pour aider les organisations \u00e0 attirer des talents provenant d\u2019industries qu\u2019elles n\u2019auraient peut-\u00eatre pas envisag\u00e9es auparavant. Ayant conscience de cette situation, RHIEC a mis au point une s\u00e9rie d\u2019outils et de ressources pour la gestion du changement. Ce concept est important, car le secteur conna\u00eet une vague de d\u00e9parts \u00e0 la retraite et une croissance simultan\u00e9e due \u00e0 l\u2019\u00e9lectrification, ce qui n\u00e9cessite un processus d\u2019int\u00e9gration et une am\u00e9lioration des comp\u00e9tences rapides.","rows":[{"acf_fc_layout":"two_columns","column_1":{"type":"text","content":"<h3>Se pr\u00e9parer au changement<\/h3>\r\n<p class=\"body-large\">Les employeur\u00b7euse\u00b7s doivent mettre en place un solide plan de rel\u00e8ve afin de veiller \u00e0 ce que les p\u00e9nuries en mati\u00e8re de comp\u00e9tences se r\u00e9sorbent, et ce, m\u00eame si elles se complexifient.<\/p>\r\nDe plus, les employeur\u00b7euse\u00b7s auront besoin d\u2019un plan de main-d\u2019\u0153uvre qui garantira que le savoir organisationnel de la g\u00e9n\u00e9ration pr\u00e9c\u00e9dente ne s\u2019envole pas avec les d\u00e9parts \u00e0 la retraite. Les outils en mati\u00e8re d\u2019encadrement et de mentorat pourraient aider \u00e0 transmettre ce savoir directement \u00e0 la prochaine g\u00e9n\u00e9ration.\r\n\r\nRessources humaines, industrie \u00e9lectrique du Canada (RHIEC) a justement cr\u00e9\u00e9 des ressources pour aider les employeur\u00b7euse\u00b7s; consultez-les ci-dessous.","aspect_ratio":"4:3","visual_accent":false,"":null,"image_id":null,"image_alt_text":""},"column_2":{"type":"image","content":"","aspect_ratio":"4_3","visual_accent":true,"":null,"image_id":46973,"image_alt_text":"Travailleur du secteur de l\u2019\u00e9lectricit\u00e9 assis sur des panneaux solaires"}}],"custom_navigation_label":""},{"acf_fc_layout":"related_posts","heading":"Ressources connexes en mati\u00e8re de gestion du changement","type":"lm_research","post_ids_all":null,"related_career_profiles":null,"related_events":null,"related_lm_research":[42300,42316,48044],"related_posts":null,"related_toolkits":null,"related_webinars":null}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Financement et incitatifs \u00e0 l\u2019embauche - EHRC<\/title>\n<meta name=\"description\" content=\"C\u2019est simple\u00a0: la plateforme Financer l\u2019avenir facilite le processus de demande et de gestion des subventions salariales et des incitatifs \u00e0 l\u2019embauche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ehrc.ca\/fr\/financement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Financement et incitatifs \u00e0 l\u2019embauche - EHRC\" \/>\n<meta property=\"og:description\" content=\"C\u2019est simple\u00a0: la plateforme Financer l\u2019avenir facilite le processus de demande et de gestion des subventions salariales et des incitatifs \u00e0 l\u2019embauche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ehrc.ca\/fr\/financement\/\" \/>\n<meta property=\"og:site_name\" content=\"EHRC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T22:53:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/financement\\\/\",\"url\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/financement\\\/\",\"name\":\"Financement et incitatifs \u00e0 l\u2019embauche - EHRC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ehrc.ca\\\/#website\"},\"datePublished\":\"2022-11-30T10:47:41+00:00\",\"dateModified\":\"2026-07-23T22:53:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/financement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ehrc.ca\\\/fr\\\/financement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/financement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ehrc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Financement et incitatifs \u00e0 l\u2019embauche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ehrc.ca\\\/#website\",\"url\":\"https:\\\/\\\/ehrc.ca\\\/\",\"name\":\"EHRC\",\"description\":\"Improving our industry, together.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ehrc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Financement et incitatifs \u00e0 l\u2019embauche - EHRC","description":"C\u2019est simple\u00a0: la plateforme Financer l\u2019avenir facilite le processus de demande et de gestion des subventions salariales et des incitatifs \u00e0 l\u2019embauche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ehrc.ca\/fr\/financement\/","og_locale":"fr_FR","og_type":"article","og_title":"Financement et incitatifs \u00e0 l\u2019embauche - EHRC","og_description":"C\u2019est simple\u00a0: la plateforme Financer l\u2019avenir facilite le processus de demande et de gestion des subventions salariales et des incitatifs \u00e0 l\u2019embauche.","og_url":"https:\/\/ehrc.ca\/fr\/financement\/","og_site_name":"EHRC","article_modified_time":"2026-07-23T22:53:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ehrc.ca\/fr\/financement\/","url":"https:\/\/ehrc.ca\/fr\/financement\/","name":"Financement et incitatifs \u00e0 l\u2019embauche - EHRC","isPartOf":{"@id":"https:\/\/ehrc.ca\/#website"},"datePublished":"2022-11-30T10:47:41+00:00","dateModified":"2026-07-23T22:53:34+00:00","breadcrumb":{"@id":"https:\/\/ehrc.ca\/fr\/financement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ehrc.ca\/fr\/financement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ehrc.ca\/fr\/financement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ehrc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Financement et incitatifs \u00e0 l\u2019embauche"}]},{"@type":"WebSite","@id":"https:\/\/ehrc.ca\/#website","url":"https:\/\/ehrc.ca\/","name":"EHRC","description":"Improving our industry, together.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ehrc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/pages\/48057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=48057"}],"version-history":[{"count":19,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/pages\/48057\/revisions"}],"predecessor-version":[{"id":56257,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/pages\/48057\/revisions\/56257"}],"wp:attachment":[{"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=48057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ehrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=48057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}